{"id":12903,"date":"2022-11-18T12:33:06","date_gmt":"2022-11-18T11:33:06","guid":{"rendered":"https:\/\/www.champagne-veuve-fourny.com\/?p=12903"},"modified":"2023-02-02T12:35:41","modified_gmt":"2023-02-02T11:35:41","slug":"champagnes-millesimes-la-grande-degustation","status":"publish","type":"post","link":"https:\/\/www.champagne-veuve-fourny.com\/en\/champagnes-millesimes-la-grande-degustation\/","title":{"rendered":"Champagnes Mill\u00e9sim\u00e9s LA GRANDE D\u00c9GUSTATION"},"content":{"rendered":"<p>The nose offers gourmand promises with its notes of yellow fruits, citrus fruits, fresh almonds and chalk. It is fleshy and smooth on the palate, bolstered by welcome hints of bitterness.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>The nose offers gourmand promises with its notes of yellow fruits, citrus fruits, fresh almonds and chalk. It is fleshy and smooth on the palate, bolstered by welcome hints of bitterness.<\/p>\n","protected":false},"author":129,"featured_media":12899,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[143],"tags":[],"class_list":["post-12903","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-le-figaro-magazine-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Champagnes Mill\u00e9sim\u00e9s LA GRANDE D\u00c9GUSTATION - Champagne Veuve Fourny<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.champagne-veuve-fourny.com\/en\/champagnes-millesimes-la-grande-degustation\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Champagnes Mill\u00e9sim\u00e9s LA GRANDE D\u00c9GUSTATION - Champagne Veuve Fourny\" \/>\n<meta property=\"og:description\" content=\"The nose offers gourmand promises with its notes of yellow fruits, citrus fruits, fresh almonds and chalk. It is fleshy and smooth on the palate, bolstered by welcome hints of bitterness.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.champagne-veuve-fourny.com\/en\/champagnes-millesimes-la-grande-degustation\/\" \/>\n<meta property=\"og:site_name\" content=\"Champagne Veuve Fourny\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Champagne-Vve-Fourny-Fils-105573037869603\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-18T11:33:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-02T11:35:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.champagne-veuve-fourny.com\/wp-content\/uploads\/2023\/02\/2301_article_le_Figaro_2211-FR-EN.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"945\" \/>\n\t<meta property=\"og:image:height\" content=\"945\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"fabian\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"fabian\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.champagne-veuve-fourny.com\\\/en\\\/champagnes-millesimes-la-grande-degustation\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.champagne-veuve-fourny.com\\\/en\\\/champagnes-millesimes-la-grande-degustation\\\/\"},\"author\":{\"name\":\"fabian\",\"@id\":\"https:\\\/\\\/www.champagne-veuve-fourny.com\\\/#\\\/schema\\\/person\\\/601321754c33c345ccf3dc34231c1e51\"},\"headline\":\"Champagnes Mill\u00e9sim\u00e9s LA GRANDE D\u00c9GUSTATION\",\"datePublished\":\"2022-11-18T11:33:06+00:00\",\"dateModified\":\"2023-02-02T11:35:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.champagne-veuve-fourny.com\\\/en\\\/champagnes-millesimes-la-grande-degustation\\\/\"},\"wordCount\":39,\"publisher\":{\"@id\":\"https:\\\/\\\/www.champagne-veuve-fourny.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.champagne-veuve-fourny.com\\\/en\\\/champagnes-millesimes-la-grande-degustation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.champagne-veuve-fourny.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/2301_article_le_Figaro_2211-FR-EN.jpg\",\"articleSection\":[\"Le Figaro Magazine\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.champagne-veuve-fourny.com\\\/en\\\/champagnes-millesimes-la-grande-degustation\\\/\",\"url\":\"https:\\\/\\\/www.champagne-veuve-fourny.com\\\/en\\\/champagnes-millesimes-la-grande-degustation\\\/\",\"name\":\"Champagnes Mill\u00e9sim\u00e9s LA GRANDE D\u00c9GUSTATION - Champagne Veuve Fourny\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.champagne-veuve-fourny.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.champagne-veuve-fourny.com\\\/en\\\/champagnes-millesimes-la-grande-degustation\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.champagne-veuve-fourny.com\\\/en\\\/champagnes-millesimes-la-grande-degustation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.champagne-veuve-fourny.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/2301_article_le_Figaro_2211-FR-EN.jpg\",\"datePublished\":\"2022-11-18T11:33:06+00:00\",\"dateModified\":\"2023-02-02T11:35:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.champagne-veuve-fourny.com\\\/en\\\/champagnes-millesimes-la-grande-degustation\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.champagne-veuve-fourny.com\\\/en\\\/champagnes-millesimes-la-grande-degustation\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.champagne-veuve-fourny.com\\\/en\\\/champagnes-millesimes-la-grande-degustation\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.champagne-veuve-fourny.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/2301_article_le_Figaro_2211-FR-EN.jpg\",\"contentUrl\":\"https:\\\/\\\/www.champagne-veuve-fourny.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/2301_article_le_Figaro_2211-FR-EN.jpg\",\"width\":945,\"height\":945,\"caption\":\"Champagnes Mill\u00e9sim\u00e9s LA GRANDE D\u00c9GUSTATION\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.champagne-veuve-fourny.com\\\/en\\\/champagnes-millesimes-la-grande-degustation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.champagne-veuve-fourny.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Champagnes Mill\u00e9sim\u00e9s LA GRANDE D\u00c9GUSTATION\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.champagne-veuve-fourny.com\\\/#website\",\"url\":\"https:\\\/\\\/www.champagne-veuve-fourny.com\\\/\",\"name\":\"Champagne Veuve Fourny\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.champagne-veuve-fourny.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.champagne-veuve-fourny.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.champagne-veuve-fourny.com\\\/#organization\",\"name\":\"Champagne Veuve Fourny & Fils\",\"url\":\"https:\\\/\\\/www.champagne-veuve-fourny.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.champagne-veuve-fourny.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.champagne-veuve-fourny.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/favicon-champagne-veuve-fourny.png\",\"contentUrl\":\"https:\\\/\\\/www.champagne-veuve-fourny.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/favicon-champagne-veuve-fourny.png\",\"width\":512,\"height\":512,\"caption\":\"Champagne Veuve Fourny & Fils\"},\"image\":{\"@id\":\"https:\\\/\\\/www.champagne-veuve-fourny.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Champagne-Vve-Fourny-Fils-105573037869603\",\"https:\\\/\\\/www.instagram.com\\\/champagneveuvefourny\\\/?hl=fr\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.champagne-veuve-fourny.com\\\/#\\\/schema\\\/person\\\/601321754c33c345ccf3dc34231c1e51\",\"name\":\"fabian\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Champagnes Mill\u00e9sim\u00e9s LA GRANDE D\u00c9GUSTATION - Champagne Veuve Fourny","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.champagne-veuve-fourny.com\/en\/champagnes-millesimes-la-grande-degustation\/","og_locale":"en_US","og_type":"article","og_title":"Champagnes Mill\u00e9sim\u00e9s LA GRANDE D\u00c9GUSTATION - Champagne Veuve Fourny","og_description":"The nose offers gourmand promises with its notes of yellow fruits, citrus fruits, fresh almonds and chalk. It is fleshy and smooth on the palate, bolstered by welcome hints of bitterness.","og_url":"https:\/\/www.champagne-veuve-fourny.com\/en\/champagnes-millesimes-la-grande-degustation\/","og_site_name":"Champagne Veuve Fourny","article_publisher":"https:\/\/www.facebook.com\/Champagne-Vve-Fourny-Fils-105573037869603","article_published_time":"2022-11-18T11:33:06+00:00","article_modified_time":"2023-02-02T11:35:41+00:00","og_image":[{"width":945,"height":945,"url":"https:\/\/www.champagne-veuve-fourny.com\/wp-content\/uploads\/2023\/02\/2301_article_le_Figaro_2211-FR-EN.jpg","type":"image\/jpeg"}],"author":"fabian","twitter_card":"summary_large_image","twitter_misc":{"Written by":"fabian","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.champagne-veuve-fourny.com\/en\/champagnes-millesimes-la-grande-degustation\/#article","isPartOf":{"@id":"https:\/\/www.champagne-veuve-fourny.com\/en\/champagnes-millesimes-la-grande-degustation\/"},"author":{"name":"fabian","@id":"https:\/\/www.champagne-veuve-fourny.com\/#\/schema\/person\/601321754c33c345ccf3dc34231c1e51"},"headline":"Champagnes Mill\u00e9sim\u00e9s LA GRANDE D\u00c9GUSTATION","datePublished":"2022-11-18T11:33:06+00:00","dateModified":"2023-02-02T11:35:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.champagne-veuve-fourny.com\/en\/champagnes-millesimes-la-grande-degustation\/"},"wordCount":39,"publisher":{"@id":"https:\/\/www.champagne-veuve-fourny.com\/#organization"},"image":{"@id":"https:\/\/www.champagne-veuve-fourny.com\/en\/champagnes-millesimes-la-grande-degustation\/#primaryimage"},"thumbnailUrl":"https:\/\/www.champagne-veuve-fourny.com\/wp-content\/uploads\/2023\/02\/2301_article_le_Figaro_2211-FR-EN.jpg","articleSection":["Le Figaro Magazine"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.champagne-veuve-fourny.com\/en\/champagnes-millesimes-la-grande-degustation\/","url":"https:\/\/www.champagne-veuve-fourny.com\/en\/champagnes-millesimes-la-grande-degustation\/","name":"Champagnes Mill\u00e9sim\u00e9s LA GRANDE D\u00c9GUSTATION - Champagne Veuve Fourny","isPartOf":{"@id":"https:\/\/www.champagne-veuve-fourny.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.champagne-veuve-fourny.com\/en\/champagnes-millesimes-la-grande-degustation\/#primaryimage"},"image":{"@id":"https:\/\/www.champagne-veuve-fourny.com\/en\/champagnes-millesimes-la-grande-degustation\/#primaryimage"},"thumbnailUrl":"https:\/\/www.champagne-veuve-fourny.com\/wp-content\/uploads\/2023\/02\/2301_article_le_Figaro_2211-FR-EN.jpg","datePublished":"2022-11-18T11:33:06+00:00","dateModified":"2023-02-02T11:35:41+00:00","breadcrumb":{"@id":"https:\/\/www.champagne-veuve-fourny.com\/en\/champagnes-millesimes-la-grande-degustation\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.champagne-veuve-fourny.com\/en\/champagnes-millesimes-la-grande-degustation\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.champagne-veuve-fourny.com\/en\/champagnes-millesimes-la-grande-degustation\/#primaryimage","url":"https:\/\/www.champagne-veuve-fourny.com\/wp-content\/uploads\/2023\/02\/2301_article_le_Figaro_2211-FR-EN.jpg","contentUrl":"https:\/\/www.champagne-veuve-fourny.com\/wp-content\/uploads\/2023\/02\/2301_article_le_Figaro_2211-FR-EN.jpg","width":945,"height":945,"caption":"Champagnes Mill\u00e9sim\u00e9s LA GRANDE D\u00c9GUSTATION"},{"@type":"BreadcrumbList","@id":"https:\/\/www.champagne-veuve-fourny.com\/en\/champagnes-millesimes-la-grande-degustation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.champagne-veuve-fourny.com\/en\/"},{"@type":"ListItem","position":2,"name":"Champagnes Mill\u00e9sim\u00e9s LA GRANDE D\u00c9GUSTATION"}]},{"@type":"WebSite","@id":"https:\/\/www.champagne-veuve-fourny.com\/#website","url":"https:\/\/www.champagne-veuve-fourny.com\/","name":"Champagne Veuve Fourny","description":"","publisher":{"@id":"https:\/\/www.champagne-veuve-fourny.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.champagne-veuve-fourny.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.champagne-veuve-fourny.com\/#organization","name":"Champagne Veuve Fourny & Fils","url":"https:\/\/www.champagne-veuve-fourny.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.champagne-veuve-fourny.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.champagne-veuve-fourny.com\/wp-content\/uploads\/2019\/08\/favicon-champagne-veuve-fourny.png","contentUrl":"https:\/\/www.champagne-veuve-fourny.com\/wp-content\/uploads\/2019\/08\/favicon-champagne-veuve-fourny.png","width":512,"height":512,"caption":"Champagne Veuve Fourny & Fils"},"image":{"@id":"https:\/\/www.champagne-veuve-fourny.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Champagne-Vve-Fourny-Fils-105573037869603","https:\/\/www.instagram.com\/champagneveuvefourny\/?hl=fr"]},{"@type":"Person","@id":"https:\/\/www.champagne-veuve-fourny.com\/#\/schema\/person\/601321754c33c345ccf3dc34231c1e51","name":"fabian"}]}},"_links":{"self":[{"href":"https:\/\/www.champagne-veuve-fourny.com\/en\/wp-json\/wp\/v2\/posts\/12903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.champagne-veuve-fourny.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.champagne-veuve-fourny.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.champagne-veuve-fourny.com\/en\/wp-json\/wp\/v2\/users\/129"}],"replies":[{"embeddable":true,"href":"https:\/\/www.champagne-veuve-fourny.com\/en\/wp-json\/wp\/v2\/comments?post=12903"}],"version-history":[{"count":1,"href":"https:\/\/www.champagne-veuve-fourny.com\/en\/wp-json\/wp\/v2\/posts\/12903\/revisions"}],"predecessor-version":[{"id":12904,"href":"https:\/\/www.champagne-veuve-fourny.com\/en\/wp-json\/wp\/v2\/posts\/12903\/revisions\/12904"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.champagne-veuve-fourny.com\/en\/wp-json\/wp\/v2\/media\/12899"}],"wp:attachment":[{"href":"https:\/\/www.champagne-veuve-fourny.com\/en\/wp-json\/wp\/v2\/media?parent=12903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.champagne-veuve-fourny.com\/en\/wp-json\/wp\/v2\/categories?post=12903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.champagne-veuve-fourny.com\/en\/wp-json\/wp\/v2\/tags?post=12903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}